{"id":84010,"date":"2025-04-24T12:33:38","date_gmt":"2025-04-24T10:33:38","guid":{"rendered":"https:\/\/hajimekarate.com\/comprar\/cinto-de-karate-para-kata-tokaido-aprovado-pela-wkf\/"},"modified":"2026-04-10T17:58:57","modified_gmt":"2026-04-10T15:58:57","slug":"cinto-de-karate-para-kata-tokaido-aprobado-pela-wkf","status":"publish","type":"product","link":"https:\/\/hajimekarate.com\/pt-pt\/comprar\/cinto-de-karate-para-kata-tokaido-aprobado-pela-wkf\/","title":{"rendered":"Cinto de Karate para Kata TOKAIDO | Aprovado pela WKF"},"content":{"rendered":"<ul>\n<li data-start=\"1050\" data-end=\"1276\">Ideal para competi\u00e7\u00f5es de kata<\/li>\n<li data-start=\"1050\" data-end=\"1276\">Cores s\u00f3lidas que n\u00e3o desbotam<\/li>\n<li data-start=\"1050\" data-end=\"1276\">Material de alta qualidade e acabamento profissional<\/li>\n<li data-start=\"1050\" data-end=\"1276\">Totalmente homologado pela WKF<\/li>\n<li data-start=\"1050\" data-end=\"1276\">Uma excelente alternativa ao cinto de kata SHUREIDO<\/li>\n<\/ul>\n<p class=\"\" data-start=\"1278\" data-end=\"1485\">En Hajime Karate te ofrecemos las mejores marcas para tu kata. Tanto TOKAIDO como SHUREIDO destacan por su calidad superior. \u00a1Elige el que mejor se adapta a tu estilo y siente la diferencia en el tatami!  <\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"\" data-start=\"470\" data-end=\"804\">Descubra o equil\u00edbrio perfeito entre design e desempenho com o cinto de kata TOKAIDO, uma escolha de confian\u00e7a para os praticantes de karat\u00e9 que procuram competir ao mais alto n\u00edvel. Este obi r\u00edgido e elegante foi certificado pela WKF (World Karate Federation), cumprindo todos os requisitos oficiais para torneios de kata. <\/p>\n<p class=\"\" data-start=\"806\" data-end=\"1048\">Gra\u00e7as \u00e0 sua cor intensa e est\u00e1vel, o cinto n\u00e3o desbota nem mancha o karategi, mantendo um aspeto impec\u00e1vel durante toda a competi\u00e7\u00e3o. O seu design t\u00e9cnico foi concebido para real\u00e7ar a forma e o dinamismo de cada movimento. <\/p>\n","protected":false},"featured_media":83942,"template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[329,3209,2401,3150,328,340],"product_tag":[2622],"class_list":{"0":"post-84010","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-cintos-competicao-wkf","7":"product_cat-cintos-tokaido","8":"product_cat-kata-concurso","9":"product_cat-tokaido-pt","10":"product_cat-cintos-karate","11":"product_cat-marcas","12":"product_tag-club-10-pt","14":"first","15":"instock","16":"taxable","17":"shipping-taxable","18":"purchasable","19":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cinto de Karate para Kata TOKAIDO | Aprovado pela WKF - Hajime Karate<\/title>\n<meta name=\"description\" content=\"Cinto de kata TOKAIDO, aprovado pela WKF. Cor resistente que n\u00e3o desbota. Ideal para competir com estilo e precis\u00e3o.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hajimekarate.com\/pt-pt\/comprar\/cinto-de-karate-para-kata-tokaido-aprobado-pela-wkf\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cinto de Karate para Kata TOKAIDO | Aprovado pela WKF - Hajime Karate\" \/>\n<meta property=\"og:description\" content=\"Cinto de kata TOKAIDO, aprovado pela WKF. Cor resistente que n\u00e3o desbota. Ideal para competir com estilo e precis\u00e3o.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hajimekarate.com\/pt-pt\/comprar\/cinto-de-karate-para-kata-tokaido-aprobado-pela-wkf\/\" \/>\n<meta property=\"og:site_name\" content=\"Hajime Karate\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-10T15:58:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hajimekarate.com\/wp-content\/uploads\/2025\/04\/cinturon-karate-kata-tokaido-wkf-azul.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hajimekarate.com\/pt-pt\/comprar\/cinto-de-karate-para-kata-tokaido-aprobado-pela-wkf\/\",\"url\":\"https:\/\/hajimekarate.com\/pt-pt\/comprar\/cinto-de-karate-para-kata-tokaido-aprobado-pela-wkf\/\",\"name\":\"Cinto de Karate para Kata TOKAIDO | Aprovado pela WKF - Hajime Karate\",\"isPartOf\":{\"@id\":\"https:\/\/hajimekarate.com\/pt-pt\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/hajimekarate.com\/pt-pt\/comprar\/cinto-de-karate-para-kata-tokaido-aprobado-pela-wkf\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/hajimekarate.com\/pt-pt\/comprar\/cinto-de-karate-para-kata-tokaido-aprobado-pela-wkf\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/hajimekarate.com\/wp-content\/uploads\/2025\/04\/cinturon-karate-kata-tokaido-wkf-azul.jpg\",\"datePublished\":\"2025-04-24T10:33:38+00:00\",\"dateModified\":\"2026-04-10T15:58:57+00:00\",\"description\":\"Cinto de kata TOKAIDO, aprovado pela WKF. Cor resistente que n\u00e3o desbota. Ideal para competir com estilo e precis\u00e3o.\",\"breadcrumb\":{\"@id\":\"https:\/\/hajimekarate.com\/pt-pt\/comprar\/cinto-de-karate-para-kata-tokaido-aprobado-pela-wkf\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hajimekarate.com\/pt-pt\/comprar\/cinto-de-karate-para-kata-tokaido-aprobado-pela-wkf\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/hajimekarate.com\/pt-pt\/comprar\/cinto-de-karate-para-kata-tokaido-aprobado-pela-wkf\/#primaryimage\",\"url\":\"https:\/\/hajimekarate.com\/wp-content\/uploads\/2025\/04\/cinturon-karate-kata-tokaido-wkf-azul.jpg\",\"contentUrl\":\"https:\/\/hajimekarate.com\/wp-content\/uploads\/2025\/04\/cinturon-karate-kata-tokaido-wkf-azul.jpg\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hajimekarate.com\/pt-pt\/comprar\/cinto-de-karate-para-kata-tokaido-aprobado-pela-wkf\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/hajimekarate.com\/pt-pt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Todos os produtos\",\"item\":\"https:\/\/hajimekarate.com\/pt-pt\/loja-karate-online\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cinto de Karate para Kata TOKAIDO | Aprovado pela WKF\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hajimekarate.com\/pt-pt\/#website\",\"url\":\"https:\/\/hajimekarate.com\/pt-pt\/\",\"name\":\"Hajime Karate\",\"description\":\"A Hajime Karate \u00e9 uma loja online especializada em produtos de karat\u00e9. Pode encontrar cintos, karateguis, protec\u00e7\u00f5es e muitos outros produtos para a sua pr\u00e1tica regular, descubra os nossos produtos agora!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hajimekarate.com\/pt-pt\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cinto de Karate para Kata TOKAIDO | Aprovado pela WKF - Hajime Karate","description":"Cinto de kata TOKAIDO, aprovado pela WKF. Cor resistente que n\u00e3o desbota. Ideal para competir com estilo e precis\u00e3o.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hajimekarate.com\/pt-pt\/comprar\/cinto-de-karate-para-kata-tokaido-aprobado-pela-wkf\/","og_locale":"pt_PT","og_type":"article","og_title":"Cinto de Karate para Kata TOKAIDO | Aprovado pela WKF - Hajime Karate","og_description":"Cinto de kata TOKAIDO, aprovado pela WKF. Cor resistente que n\u00e3o desbota. Ideal para competir com estilo e precis\u00e3o.","og_url":"https:\/\/hajimekarate.com\/pt-pt\/comprar\/cinto-de-karate-para-kata-tokaido-aprobado-pela-wkf\/","og_site_name":"Hajime Karate","article_modified_time":"2026-04-10T15:58:57+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/hajimekarate.com\/wp-content\/uploads\/2025\/04\/cinturon-karate-kata-tokaido-wkf-azul.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hajimekarate.com\/pt-pt\/comprar\/cinto-de-karate-para-kata-tokaido-aprobado-pela-wkf\/","url":"https:\/\/hajimekarate.com\/pt-pt\/comprar\/cinto-de-karate-para-kata-tokaido-aprobado-pela-wkf\/","name":"Cinto de Karate para Kata TOKAIDO | Aprovado pela WKF - Hajime Karate","isPartOf":{"@id":"https:\/\/hajimekarate.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hajimekarate.com\/pt-pt\/comprar\/cinto-de-karate-para-kata-tokaido-aprobado-pela-wkf\/#primaryimage"},"image":{"@id":"https:\/\/hajimekarate.com\/pt-pt\/comprar\/cinto-de-karate-para-kata-tokaido-aprobado-pela-wkf\/#primaryimage"},"thumbnailUrl":"https:\/\/hajimekarate.com\/wp-content\/uploads\/2025\/04\/cinturon-karate-kata-tokaido-wkf-azul.jpg","datePublished":"2025-04-24T10:33:38+00:00","dateModified":"2026-04-10T15:58:57+00:00","description":"Cinto de kata TOKAIDO, aprovado pela WKF. Cor resistente que n\u00e3o desbota. Ideal para competir com estilo e precis\u00e3o.","breadcrumb":{"@id":"https:\/\/hajimekarate.com\/pt-pt\/comprar\/cinto-de-karate-para-kata-tokaido-aprobado-pela-wkf\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hajimekarate.com\/pt-pt\/comprar\/cinto-de-karate-para-kata-tokaido-aprobado-pela-wkf\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/hajimekarate.com\/pt-pt\/comprar\/cinto-de-karate-para-kata-tokaido-aprobado-pela-wkf\/#primaryimage","url":"https:\/\/hajimekarate.com\/wp-content\/uploads\/2025\/04\/cinturon-karate-kata-tokaido-wkf-azul.jpg","contentUrl":"https:\/\/hajimekarate.com\/wp-content\/uploads\/2025\/04\/cinturon-karate-kata-tokaido-wkf-azul.jpg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/hajimekarate.com\/pt-pt\/comprar\/cinto-de-karate-para-kata-tokaido-aprobado-pela-wkf\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hajimekarate.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Todos os produtos","item":"https:\/\/hajimekarate.com\/pt-pt\/loja-karate-online\/"},{"@type":"ListItem","position":3,"name":"Cinto de Karate para Kata TOKAIDO | Aprovado pela WKF"}]},{"@type":"WebSite","@id":"https:\/\/hajimekarate.com\/pt-pt\/#website","url":"https:\/\/hajimekarate.com\/pt-pt\/","name":"Hajime Karate","description":"A Hajime Karate \u00e9 uma loja online especializada em produtos de karat\u00e9. Pode encontrar cintos, karateguis, protec\u00e7\u00f5es e muitos outros produtos para a sua pr\u00e1tica regular, descubra os nossos produtos agora!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hajimekarate.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"}]}},"_links":{"self":[{"href":"https:\/\/hajimekarate.com\/pt-pt\/wp-json\/wp\/v2\/product\/84010","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hajimekarate.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/hajimekarate.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hajimekarate.com\/pt-pt\/wp-json\/wp\/v2\/media\/83942"}],"wp:attachment":[{"href":"https:\/\/hajimekarate.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=84010"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/hajimekarate.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=84010"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/hajimekarate.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=84010"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/hajimekarate.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=84010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}