{"id":8160,"date":"2018-09-09T18:24:11","date_gmt":"2018-09-09T16:24:11","guid":{"rendered":"https:\/\/hajimekarate.com\/comprar\/t-shirt-top-tagoya-sem-carcaca\/"},"modified":"2025-05-27T09:46:09","modified_gmt":"2025-05-27T07:46:09","slug":"top-para-protecao-de-peito-tagoya-homologado-rfek","status":"publish","type":"product","link":"https:\/\/hajimekarate.com\/pt-pt\/comprar\/top-para-protecao-de-peito-tagoya-homologado-rfek\/","title":{"rendered":"Top para Prote\u00e7\u00e3o de Peito Feminino Tagoya Homologado RFEK"},"content":{"rendered":"<p><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Top de Tagoya para levar baixo do fato&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:769,&quot;3&quot;:{&quot;1&quot;:0},&quot;11&quot;:4,&quot;12&quot;:0}\">Top de Tagoya para levar baixo do fato<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Top para prote\u00e7\u00e3o de peito feminino para Karat\u00e9 da marca Tagaoya homologado pela Real Federa\u00e7\u00e3o Espanhola de Karat\u00e9 (RFEK). Sem a prote\u00e7\u00e3o pl\u00e1stica para o peito. Homologada pela RFEK.<\/p>\n","protected":false},"featured_media":9555,"template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[2399,344,343],"product_tag":[2737],"class_list":{"0":"post-8160","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-kumite-concurso","7":"product_cat-homologadas-rfek","8":"product_cat-protecoes-pt","9":"product_tag-club-12-pt-pt","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-variable"},"_links":{"self":[{"href":"https:\/\/hajimekarate.com\/pt-pt\/wp-json\/wp\/v2\/product\/8160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hajimekarate.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/hajimekarate.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hajimekarate.com\/pt-pt\/wp-json\/wp\/v2\/media\/9555"}],"wp:attachment":[{"href":"https:\/\/hajimekarate.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=8160"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/hajimekarate.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=8160"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/hajimekarate.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=8160"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/hajimekarate.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=8160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}