{"id":8128,"date":"2018-09-09T18:24:42","date_gmt":"2018-09-09T16:24:42","guid":{"rendered":"https:\/\/hajimekarate.com\/comprar\/luvas-shureido-vermelhas-o-azuis-homologadas-pela-wkf\/"},"modified":"2026-08-25T09:58:46","modified_gmt":"2026-08-25T07:58:46","slug":"luvas-shureido-vermelhas-azuis","status":"publish","type":"product","link":"https:\/\/hajimekarate.com\/pt-pt\/comprar\/luvas-shureido-vermelhas-azuis\/","title":{"rendered":"Luvas Shureido Vermelhas ou Azuis"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Luvas Shureido Vermelhas ou Azuis<\/p>\n<p><em>*As prote\u00e7\u00f5es da SHUREIDO j\u00e1 n\u00e3o s\u00e3o homologadas pela WKF. <\/em><\/p>\n","protected":false},"featured_media":8130,"template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[1892,2399,1374,344,343],"product_tag":[2967],"class_list":{"0":"post-8128","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-competidores-de-pouso-de-equipamentos-de-alta-competicao","7":"product_cat-kumite-concurso","8":"product_cat-promocoes-pt-pt","9":"product_cat-homologadas-rfek","10":"product_cat-protecoes-pt","11":"product_tag-club-42-pt","13":"first","14":"instock","15":"sale","16":"taxable","17":"shipping-taxable","18":"purchasable","19":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Luvas Shureido Vermelhas ou Azuis - Hajime Karate<\/title>\n<meta name=\"description\" content=\"Compra online luvas Shureido vermelhas ou azuis homologadas pela Federa\u00e7\u00e3o Mundial de Karate - WKF. Todos os tamanhos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hajimekarate.com\/pt-pt\/comprar\/luvas-shureido-vermelhas-azuis\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Luvas Shureido Vermelhas ou Azuis - Hajime Karate\" \/>\n<meta property=\"og:description\" content=\"Compra online luvas Shureido vermelhas ou azuis homologadas pela Federa\u00e7\u00e3o Mundial de Karate - WKF. Todos os tamanhos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hajimekarate.com\/pt-pt\/comprar\/luvas-shureido-vermelhas-azuis\/\" \/>\n<meta property=\"og:site_name\" content=\"Hajime Karate\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-25T07:58:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hajimekarate.com\/wp-content\/uploads\/2018\/09\/guantillas-azules-shureido-karate-wkf.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hajimekarate.com\/pt-pt\/comprar\/luvas-shureido-vermelhas-azuis\/\",\"url\":\"https:\/\/hajimekarate.com\/pt-pt\/comprar\/luvas-shureido-vermelhas-azuis\/\",\"name\":\"Luvas Shureido Vermelhas ou Azuis - Hajime Karate\",\"isPartOf\":{\"@id\":\"https:\/\/hajimekarate.com\/pt-pt\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/hajimekarate.com\/pt-pt\/comprar\/luvas-shureido-vermelhas-azuis\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/hajimekarate.com\/pt-pt\/comprar\/luvas-shureido-vermelhas-azuis\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/hajimekarate.com\/wp-content\/uploads\/2018\/09\/guantillas-azules-shureido-karate-wkf.jpg\",\"datePublished\":\"2018-09-09T16:24:42+00:00\",\"dateModified\":\"2026-08-25T07:58:46+00:00\",\"description\":\"Compra online luvas Shureido vermelhas ou azuis homologadas pela Federa\u00e7\u00e3o Mundial de Karate - WKF. Todos os tamanhos.\",\"breadcrumb\":{\"@id\":\"https:\/\/hajimekarate.com\/pt-pt\/comprar\/luvas-shureido-vermelhas-azuis\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hajimekarate.com\/pt-pt\/comprar\/luvas-shureido-vermelhas-azuis\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/hajimekarate.com\/pt-pt\/comprar\/luvas-shureido-vermelhas-azuis\/#primaryimage\",\"url\":\"https:\/\/hajimekarate.com\/wp-content\/uploads\/2018\/09\/guantillas-azules-shureido-karate-wkf.jpg\",\"contentUrl\":\"https:\/\/hajimekarate.com\/wp-content\/uploads\/2018\/09\/guantillas-azules-shureido-karate-wkf.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"luvas-azuis-shureido-karate-wkf\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hajimekarate.com\/pt-pt\/comprar\/luvas-shureido-vermelhas-azuis\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/hajimekarate.com\/pt-pt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Todos os produtos\",\"item\":\"https:\/\/hajimekarate.com\/pt-pt\/loja-karate-online\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Luvas Shureido Vermelhas ou Azuis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hajimekarate.com\/pt-pt\/#website\",\"url\":\"https:\/\/hajimekarate.com\/pt-pt\/\",\"name\":\"Hajime Karate\",\"description\":\"A Hajime Karate \u00e9 uma loja online especializada em produtos de karat\u00e9. Pode encontrar cintos, karateguis, protec\u00e7\u00f5es e muitos outros produtos para a sua pr\u00e1tica regular, descubra os nossos produtos agora!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hajimekarate.com\/pt-pt\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Luvas Shureido Vermelhas ou Azuis - Hajime Karate","description":"Compra online luvas Shureido vermelhas ou azuis homologadas pela Federa\u00e7\u00e3o Mundial de Karate - WKF. Todos os tamanhos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hajimekarate.com\/pt-pt\/comprar\/luvas-shureido-vermelhas-azuis\/","og_locale":"pt_PT","og_type":"article","og_title":"Luvas Shureido Vermelhas ou Azuis - Hajime Karate","og_description":"Compra online luvas Shureido vermelhas ou azuis homologadas pela Federa\u00e7\u00e3o Mundial de Karate - WKF. Todos os tamanhos.","og_url":"https:\/\/hajimekarate.com\/pt-pt\/comprar\/luvas-shureido-vermelhas-azuis\/","og_site_name":"Hajime Karate","article_modified_time":"2026-08-25T07:58:46+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/hajimekarate.com\/wp-content\/uploads\/2018\/09\/guantillas-azules-shureido-karate-wkf.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hajimekarate.com\/pt-pt\/comprar\/luvas-shureido-vermelhas-azuis\/","url":"https:\/\/hajimekarate.com\/pt-pt\/comprar\/luvas-shureido-vermelhas-azuis\/","name":"Luvas Shureido Vermelhas ou Azuis - Hajime Karate","isPartOf":{"@id":"https:\/\/hajimekarate.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hajimekarate.com\/pt-pt\/comprar\/luvas-shureido-vermelhas-azuis\/#primaryimage"},"image":{"@id":"https:\/\/hajimekarate.com\/pt-pt\/comprar\/luvas-shureido-vermelhas-azuis\/#primaryimage"},"thumbnailUrl":"https:\/\/hajimekarate.com\/wp-content\/uploads\/2018\/09\/guantillas-azules-shureido-karate-wkf.jpg","datePublished":"2018-09-09T16:24:42+00:00","dateModified":"2026-08-25T07:58:46+00:00","description":"Compra online luvas Shureido vermelhas ou azuis homologadas pela Federa\u00e7\u00e3o Mundial de Karate - WKF. Todos os tamanhos.","breadcrumb":{"@id":"https:\/\/hajimekarate.com\/pt-pt\/comprar\/luvas-shureido-vermelhas-azuis\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hajimekarate.com\/pt-pt\/comprar\/luvas-shureido-vermelhas-azuis\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/hajimekarate.com\/pt-pt\/comprar\/luvas-shureido-vermelhas-azuis\/#primaryimage","url":"https:\/\/hajimekarate.com\/wp-content\/uploads\/2018\/09\/guantillas-azules-shureido-karate-wkf.jpg","contentUrl":"https:\/\/hajimekarate.com\/wp-content\/uploads\/2018\/09\/guantillas-azules-shureido-karate-wkf.jpg","width":1000,"height":1000,"caption":"luvas-azuis-shureido-karate-wkf"},{"@type":"BreadcrumbList","@id":"https:\/\/hajimekarate.com\/pt-pt\/comprar\/luvas-shureido-vermelhas-azuis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hajimekarate.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Todos os produtos","item":"https:\/\/hajimekarate.com\/pt-pt\/loja-karate-online\/"},{"@type":"ListItem","position":3,"name":"Luvas Shureido Vermelhas ou Azuis"}]},{"@type":"WebSite","@id":"https:\/\/hajimekarate.com\/pt-pt\/#website","url":"https:\/\/hajimekarate.com\/pt-pt\/","name":"Hajime Karate","description":"A Hajime Karate \u00e9 uma loja online especializada em produtos de karat\u00e9. Pode encontrar cintos, karateguis, protec\u00e7\u00f5es e muitos outros produtos para a sua pr\u00e1tica regular, descubra os nossos produtos agora!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hajimekarate.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"}]}},"_links":{"self":[{"href":"https:\/\/hajimekarate.com\/pt-pt\/wp-json\/wp\/v2\/product\/8128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hajimekarate.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/hajimekarate.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hajimekarate.com\/pt-pt\/wp-json\/wp\/v2\/media\/8130"}],"wp:attachment":[{"href":"https:\/\/hajimekarate.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=8128"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/hajimekarate.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=8128"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/hajimekarate.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=8128"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/hajimekarate.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=8128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}