{"id":44977,"date":"2018-09-04T21:36:54","date_gmt":"2018-09-04T19:36:54","guid":{"rendered":"https:\/\/hajimekarate.com\/comprar\/cinture-kaiten-basic-monocolor\/"},"modified":"2026-03-06T16:35:57","modified_gmt":"2026-03-06T15:35:57","slug":"cinture-karate-colorate","status":"publish","type":"product","link":"https:\/\/hajimekarate.com\/it\/acquistare\/cinture-karate-colorate\/","title":{"rendered":"Kaiten"},"content":{"rendered":"<div class=\"woocommerce-tabs wc-tabs-wrapper full-width-tabs\" data-tab-style=\"fullwidth\">\n<div id=\"tab-description\" class=\"panel entry-content\">\n<p>Cinture di karate monocolore, 100 % cotone. Il peso varia da 250 a 500 grammi, a seconda della dimensione scelta. Sono realizzati in cotone di qualit\u00e0 che conferisce loro uno spessore perfetto per la pratica del karate nel dojo.<\/p>\n<p>Le cinture nel Karate indicano il grado del karateka che le detiene. Identifica il loro livello di tecnica, abilit\u00e0 ed esperienza. I colori delle cinture variano talvolta a seconda della federazione o del ramo del Karate praticato. Il sistema di gradi delle cinture di karate \u00e8 chiamato Kyu o gradi Kyu. D&#8217;altra parte, i gradi Dan esistenti nel Karate sono stati integrati prendendo come riferimento un&#8217;altra arte marziale, il judo di origine giapponese. I gradi Dan sono il grado pi\u00f9 alto nella pratica del Karate e si riflettono nelle cinture nere del Karate (dal 1\u00b0 al 10\u00b0 DAN). Quali sono i gradi Kyu? Bianco &#8211; 10\u00b0 Kyu, Giallo &#8211; 9\u00b0 Kyu, Arancione &#8211; 8\u00b0 e 7\u00b0 Kyu, Verde &#8211; 6\u00b0 e 5\u00b0 Kyu, Blu &#8211; 4\u00b0 e 3\u00b0 Kyu, Marrone &#8211; 2\u00b0 e 1\u00b0 Kyu.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<div class=\"clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Cinture da karate basiche colorate per gli esami di grado kyu. Disponibili nelle marche Kaiten e Hajime. Realizzate in cotone 100% con finiture di alta qualit\u00e0.  <\/p>\n","protected":false},"featured_media":38140,"template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[2659,2707,2663,3368],"product_tag":[2957],"class_list":{"0":"post-44977","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-cinture-da-karate","7":"product_cat-cinture-kaiten","8":"product_cat-kaiten-it","9":"product_cat-cinture-di-colore","10":"product_tag-club-50-it","12":"first","13":"instock","14":"taxable","15":"shipping-taxable","16":"purchasable","17":"product-type-variable","18":"has-default-attributes"},"_links":{"self":[{"href":"https:\/\/hajimekarate.com\/it\/wp-json\/wp\/v2\/product\/44977","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hajimekarate.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/hajimekarate.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hajimekarate.com\/it\/wp-json\/wp\/v2\/media\/38140"}],"wp:attachment":[{"href":"https:\/\/hajimekarate.com\/it\/wp-json\/wp\/v2\/media?parent=44977"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/hajimekarate.com\/it\/wp-json\/wp\/v2\/product_brand?post=44977"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/hajimekarate.com\/it\/wp-json\/wp\/v2\/product_cat?post=44977"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/hajimekarate.com\/it\/wp-json\/wp\/v2\/product_tag?post=44977"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}